{"id":487,"date":"2012-11-05T19:12:33","date_gmt":"2012-11-05T18:12:33","guid":{"rendered":"https:\/\/gratkowski.com\/wordpress\/?p=487"},"modified":"2014-11-23T18:58:06","modified_gmt":"2014-11-23T17:58:06","slug":"four-alto-4-compositions-by-frank-gratkowski","status":"publish","type":"post","link":"http:\/\/gratkowski.com\/de\/recordings\/four-alto-4-compositions-by-frank-gratkowski\/","title":{"rendered":"Fo[u]r Alto &#8222;4 compositions by frank gratkowski&#8220;"},"content":{"rendered":"<p><a href=\"https:\/\/gratkowski.com\/wordpress\/recordings\/four-alto-4-compositions-by-frank-gratkowski\/\"><img decoding=\"async\" loading=\"lazy\" class=\"alignright\" title=\"fouralto_250\" src=\"https:\/\/gratkowski.com\/wordpress\/wp-content\/uploads\/2012\/11\/fouralto_250.jpg\" alt=\"\" width=\"250\" height=\"250\" \/><\/a><\/p>\n<p>Florian Bergmann,<br \/>\nFrank Gratkowski,<br \/>\nBenjamin Weidekamp,<br \/>\nChristian Weidner &#8211; alto saxophones<\/p>\n<p><!--more--><\/p>\n<p><a href=\"http:\/\/www.leorecords.com\/?m=select&amp;id=CD_LR_652\" target=\"_blank\">Leo Records (LR 652)<\/a><\/p>\n<p>1 TamTam 4a (15:20)<br \/>\n2 Molto Fluttuante (11:38)<br \/>\n3 Likewise (4:37)<br \/>\n4 Sound 1 (31:10)<\/p>\n<p>Recorded on April 4th and 5th 2011 by Walter Quintus. Mixed and mastered by Walter Quintus.<\/p>\n<p>All compositions by Frank Gratkowski (GEMA)<\/p>\n<p>Special thanks to Reinhard, Achim, Gabriele and Hayden<\/p>\n<p>Cover art by Gabriele D.R. Guenther<\/p>\n<p>&#8222;Questions &amp; Answers&#8220; (detail)<\/p>\n<p>mixed media\/found objects on canvas on wood &#8212; 160 x 61 cm<\/p>\n<p>Artwork photograpy by Achim Kaufmann<\/p>\n<p>Frontcover design by Manon Kahle<\/p>\n<h3>Liner Notes:\u00a0EINKLANG DES VIELF\u00c4LTIGEN<\/h3>\n<p>Das Saxophonquartett \u201eFo[u]r Alto\u201c auf mikrotonalen Wegen<\/p>\n<p>Seit den 1970er-Jahren kommen Saxophone immer wieder in selbst\u00e4ndigen Ensembles zum Einsatz. Legend\u00e4r ist das 1973 gegr\u00fcndete Trio SOS (Alan Skidmore, John Surman und Mike Osborne), eines der ersten Saxophonensembles, das ohne obligatorische Rhythmusgruppe spielte, dem bald darauf, 1976, mit dem \u201eWorld Saxophone Quartet\u201c (in der Originalbesetzung: David Murray, Oliver Lake, Julius Hemphill und Hamiet Bluiett) die wohl bekannteste Saxophongruppe folgte. Das sollte den Startschuss geben f\u00fcr die Gr\u00fcndung zahlreicher weiterer reiner Saxophonensembles, zu deren bekanntesten das \u201eRova Saxophone Quartet\u201c und in Deutschland die \u201eK\u00f6lner Saxophon Mafia\u201c z\u00e4hlen.<\/p>\n<p>All diesen Ensembles gemeinsam ist eine Form des dialogischen Spiels, in dem drei Solisten wechselseitig die Phrasen formen, angetrieben meist von groovenden Ostinati eines Baritonsaxophons, das auch das harmonische Grundger\u00fcst der Improvisationen liefert. Wie anders ist hingegen das 2008 gegr\u00fcndete Saxophonquartett \u201eFo[u]r Alto\u201c strukturiert: nicht im Sinne des Dialogprinzips, sondern mit dem Ziel, die Kl\u00e4nge zu verschmelzen, um aus vier Stimmen gleichsam eine einzige, vielf\u00e4ltig bereicherte zu machen.<\/p>\n<p>Ein gravierender Unterschied zu den bisher bekannten Saxophonquartetten liegt bereits in der Besetzung. W\u00e4hrend in den meisten Saxophonensembles die gesamte Palette der Saxophonkl\u00e4nge \u2013 vom Sopran-, \u00fcber das Alt- und Tenorsaxophon bis zum Bariton- oder gar Basssaxophon (wie etwa bei Anthony Braxton) \u2013 genutzt wird, verwendet \u201eFo[u]r Alto\u201c schlicht vier Altsaxophone. Wer glaubt, dadurch w\u00fcrde der Sound des Quartetts monochrom, der irrt jedoch gewaltig. Denn der asketischen Beschr\u00e4nkung des Instrumentariums korrespondiert eine enorme Erweiterung des harmonischen Spektrums: durch den Einsatz mikrointervallischer Konzepte.<\/p>\n<p>Seit Andreas Werckmeister Ende des 17. Jahrhunderts die gleichm\u00e4\u00dfig temperierte Stimmung entwickelte, dominiert das darauf basierende Tonsystem die westliche Musik derart, dass vielen H\u00f6rern gar nicht mehr bewusst ist, dass noch bis ins 18. Jahrhundert hinein zw\u00f6lf konkurrierende Kirchentonarten verwendet wurden, die mit jeweils spezifischen Klangfarben ausgestattet sind und dementsprechend f\u00fcr verschiedene kompositorische Zwecke eingesetzt wurden. So erweiternd die auf der wohltemperierten Stimmung basierenden Tonskalen hinsichtlich ihrer Modulationsf\u00e4higkeit sind, so einschr\u00e4nkend sind sie f\u00fcr die Entwicklung eigent\u00fcmlicher Klangcharakteristika. Bei allen Vorz\u00fcgen besitzt die Unterteilung des Oktavraums in zw\u00f6lf gleichm\u00e4\u00dfig temperierte Halbtonschritte nat\u00fcrlich auch etwas Willk\u00fcrliches.<\/p>\n<p>In der neuen Musik sind diese Limitationen vollends bewusst geworden. Bereits zu Beginn des 20. Jahrhunderts versuchten Komponisten wie Alois H\u00e1ba oder Ivan Wyschnegradsky durch Entwicklung von Viertel- und Sechsteltonskalen neue Farben ins kompositorische Spiel zu bringen. Mit einer mathematisch berechneten, aus 43 T\u00f6nen bestehenden mikrotonalen Tonskala agierte seit den 1930er Jahren der Amerikaner Harry Partch; etwas sp\u00e4ter entwickelte sein Landsmann James Tenney speziell auf bestimmte Kompositionen zugeschnittene Skalen; mit dem gesamten Spektrum der Obert\u00f6ne operieren heute die franz\u00f6sische \u201eEcole spectrale\u201c oder der \u00d6sterreicher Georg Friedrich Haas. Womit nun auch in die westliche Musik eindrang, was in der arabischen seit jeher eine Selbstverst\u00e4ndlichkeit ist: Intervalle einzusetzen, die kleiner sind als ein Halbtonschritt, was in der orientalischen Musik mit den so genannten Maq\u0101m\u0101t, Melodiemodellen, die Viertelt\u00f6ne enthalten, praktiziert wird.<\/p>\n<p>Diese Integration von Mikrointervallen treiben auch jene Improvisationsmusiker voran, die sich hinter dem doppeldeutigen Titel \u201eFo[u]r Alto\u201c verbergen: Die vier in Berlin beheimateten Altsaxophonisten Frank Gratkowski, Christian Weidner, Benjamin Weidekamp und Florian Bergmann spielen St\u00fccke \u201efor alto\u201c \u2013 also gleichsam f\u00fcr e i n Altsaxophon \u2013, und das, obwohl sie mit Viertelt\u00f6nen experimentieren. Begonnen hatte das Quartett seine Entdeckungsreise, indem es v\u00f6llig frei mit Mikrointervallen improvisierte. Weil er von den Ergebnissen dieser Improvisationen nicht restlos \u00fcberzeugt war, beschloss Frank Gratkowski nach dem ersten Konzert des Ensembles im M\u00e4rz 2009 in Berlin, von Improvisationen durchsetzte mikrotonale Kompositionen f\u00fcr das Ensemble zu schreiben. Und das Ergebnis seiner \u2013 auch auf Spektralanalysen und mathematischen Kalkulationen basierenden \u2013 Klangforschungen kann sich h\u00f6ren lassen.<\/p>\n<p>Die hintersinnige Verschmelzung von Spaltkl\u00e4ngen (\u201emultiphonics\u201c) zu einem singul\u00e4ren, prismatisch schillernden Klangkristall gelingt dem Quartett in dem mit enormer Konzentration gespielten Schlussst\u00fcck \u201eSound 1\u201c am eindrucksvollsten: 24 Spaltkl\u00e4nge werden in 24 unterschiedlich definierten Dauern permutierend von jedem der vier Spieler so intoniert, dass der Fluss der Ateml\u00e4ngen sich derart organisch entwickelt, als w\u00fcrde nur ein Spieler all diese Kl\u00e4nge erzeugen. Indem die vier Musiker sich bei der Auff\u00fchrung um das Publikum herum platzieren, erh\u00e4lt \u201eSound 1\u201c auch eine \u00e4hnliche Plastizit\u00e4t wie etwa John Cages Blasorchesterst\u00fcck \u201eFifty Eight\u201c.<\/p>\n<p>Was aber am meisten \u00fcberrascht an den vier St\u00fccken dieser CD, ist deren Vielf\u00e4ltigkeit. Die Obertonschwingungen der Multiphonics in \u201eSound 1\u201c bilden blo\u00df e i n e Methode, um das intendierte Ziel zu erreichen, vier Altsaxophone zu einem Instrument verschmelzen zu lassen. Ganz anders sind hingegen die drei anderen St\u00fccke Gratkowskis organisiert. In \u201eMolto fluttuante\u201c steuern die vier Musiker mit rhythmisch immer komplexer werdenden Phrasen harmonische Haltepunkte an, bis am Ende die Synchronizit\u00e4t zu zerbrechen beginnt und in eine Improvisation mit Atemger\u00e4uschen m\u00fcndet. Im nahtlos daran anschlie\u00dfenden \u201eLikewise\u201c sind die Rhythmen der vier Stimmen wiederum streng im Gleichma\u00df gef\u00fchrt, harmonisch jedoch so aufgef\u00e4chert, dass die Mikrointervalle oft geradezu schmerzhaft hervorstechen. Als \u201euni-rhythmischen Kanon\u201c bezeichnet Gratkowski selbst diese Verfahrensweise, die erst am Ende des St\u00fccks in einer gleichsam antiphonal angelegten, aus punktuell angeblasenen T\u00f6nen bestehenden Passage aufgebrochen wird.<\/p>\n<p>Als eine Art Summe all dieser Techniken ist Gratkowskis erste Komposition zu verstehen, \u201eTam Tam 4a\u201c, die genau genommen aus sieben, mittels strukturierter Improvisationen miteinander verbundenen kurzen St\u00fccken besteht. Besonders signifikant ist eine dieser Improvisationen mit kurz artikulierten T\u00f6nen, die den Eindruck erweckt, als lie\u00dfe jemand ein Tonband bei angelegtem Tonkopf r\u00fcckw\u00e4rts abspielen, und das St\u00fcck \u201eLines-Gong M\u201c, das durch die raffinierte Verzahnung von Triolen, Quintolen, Sextolen und Septolen auseinanderzubersten scheint, obwohl das St\u00fcck streng organisiert ist. Da verschmilzt die Magie schwerelos scheinender asiatischer Musik aufs Sch\u00f6nste mit den rationalen Kompositionstechniken des Westens, ohne dass deren Rigidit\u00e4t dem H\u00f6rer bewusst w\u00fcrde. Um ihn gerade dadurch zu verf\u00fchren, in ebenso fremde wie faszinierende Klangwelten einzutauchen.<\/p>\n<p>Reinhard Kager<\/p>\n<div><\/div>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Florian Bergmann, Frank Gratkowski, Benjamin Weidekamp, Christian Weidner &#8211; alto saxophones<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1],"tags":[],"acf":[],"_links":{"self":[{"href":"http:\/\/gratkowski.com\/de\/wp-json\/wp\/v2\/posts\/487"}],"collection":[{"href":"http:\/\/gratkowski.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/gratkowski.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/gratkowski.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/gratkowski.com\/de\/wp-json\/wp\/v2\/comments?post=487"}],"version-history":[{"count":9,"href":"http:\/\/gratkowski.com\/de\/wp-json\/wp\/v2\/posts\/487\/revisions"}],"predecessor-version":[{"id":490,"href":"http:\/\/gratkowski.com\/de\/wp-json\/wp\/v2\/posts\/487\/revisions\/490"}],"wp:attachment":[{"href":"http:\/\/gratkowski.com\/de\/wp-json\/wp\/v2\/media?parent=487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/gratkowski.com\/de\/wp-json\/wp\/v2\/categories?post=487"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/gratkowski.com\/de\/wp-json\/wp\/v2\/tags?post=487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}